{"id":41914,"date":"2022-03-11T09:05:10","date_gmt":"2022-03-11T09:05:10","guid":{"rendered":"https:\/\/g9hq0oamq8.onrocket.site\/method\/gamification\/"},"modified":"2022-05-26T19:53:47","modified_gmt":"2022-05-26T19:53:47","slug":"gamification","status":"publish","type":"methode","link":"https:\/\/www.innovation.wiki\/de\/method\/gamification\/","title":{"rendered":"Gamification"},"content":{"rendered":"<p>Gamification ist eine spielerische Wissensvermittlung, durch die Sie Inhalte und Aufgaben auf innovative Art und Weise transportieren.<br \/>\nMit den spieletypischen, unterhaltsamen Mechanismen vermittelt die Methode Informationen und vielf\u00e4ltige weitere Zusammenh\u00e4nge. Ziele sind Wissensanreicherung sowie Motivation und Verhaltens\u00e4nderungen f\u00fcr die unterschiedlichsten Zielgruppen. Gamification ist abgeleitet aus den dem englischen: \u201eGame\u201c \u2013 \u201edas Spiel\u201c. Zu den spieltypischen Elementen z\u00e4hlen, neben der Bew\u00e4ltigung von Aufgaben durch individuelle oder kollaborative<br \/>\nLeistungen, Regeln, Punkte, Preise und Vergleiche. Die Werbebranche nutzte Gamification zuerst f\u00fcr ihre Zwecke. Durch den gro\u00dfen Erfolg setzte sich die Methode in vielen Bereichen durch, in denen ein kurzweiliges Infotainment zielf\u00fchrend ist. So wird Gamification heute zum Beispiel beim Online-Shopping,<br \/>\nin der Fitness-Branche und im Bildungssektor eingesetzt. Der Erfolg beruht in erster Linie auf den Spieltrieb des Menschen, da die spielerischen Erlebnisse positive Emotionen ausl\u00f6sen. Die digitalen Komponenten verst\u00e4rken diesen Effekt, da die Belohnung, oft in Form von Punkten und positiven Rankings, unmittelbar erfolgt. Gamification findet zumeist auf digitalen Kan\u00e4len per Smartphone, Notebook oder PC statt, jedoch kann die Methode auch in klassischen Formen angewendet werden. Agile Managementmethoden nutzen zwecks kreativer Ideenfindung ebenfalls Gamification.<br \/>\nGamification wird auch h\u00e4ufig im Bereich der Schulung und Motivation von Mitarbeitern eingesetzt. Hat man erst einmal seine Ausbildung oder sein Studium vollendet, ist eine kontinuierliche Weiterbildung nicht selbstverst\u00e4ndlich, gleichwohl ist Wissenserweiterung in einer sich immer schneller digital transformierenden Welt zwingend notwendig. Die Belohnungssysteme von Gamification motivieren Mitarbeiter zu einer Teilnahme an solchen Bildungsma\u00dfnahmen. Im Vertrieb bildet der oft integrierte Wettbewerbscharakter ein Anreiz, sich mit den Kollegen zu \u201echallengen\u201c: Ranglisten spiegeln Verkaufserfolge wider und steigern den Konkurrenzkampf. Jeder m\u00f6chte gewinnen und seine Belohnung erhalten. Dieses ist zugleich der Grund, warum Personalf\u00fchrung und Betriebsr\u00e4te an der Planung von Gamification-Anwendungen teilhaben m\u00fcssen \u2013 die Ergebnisse sind messbar und durch die<br \/>\ndigitalen Anwendungen Gamification ist aus Innovationsworkshops nicht mehr wegzudenken. Spielen ist im Grunde ein anderes Wort f\u00fcr Lernen; betrachten wir nur einmal unsere Kinder. Alles, was sie aus sich heraus tun, ist spielerisch \u2013 und sie lernen dadurch alles, was sie in unserer Gesellschaft zum \u00dcberleben brauchen.<\/p>\n<p>Im Grunde lieben wir es alle zu spielen \u2013 es wird uns nur mit der Zeit aberzogen. Arbeit ist Arbeit und Spiel ist Spiel, das ist es, was wir in der Schule beigebracht bekommen. Aber jeder von uns wei\u00df aus eigener Erfahrung: Die Dinge, die besonders viel Spa\u00df gemacht haben, bleiben in Erinnerung \u2013 alles andere verblasst.<\/p>\n<p>Einige haben es sich bewahrt \u2013 vielleicht kennen besonders die Kreativen den Zustand des \u201eFlows\u201c, n\u00e4mlich mit Begeisterung einer Aufgabe nachzugehen und alles um sich herum zu vergessen. Und so besonders schnell zum Ziel zu gelangen. Wenn dieser Zustand im Job erreicht wird, liegt es auf der Hand, dass die Zufriedenheit besonders hoch und die Ergebnisse besonders gut sind.<\/p>\n<p>Gamification ist die Einbindung von Spielprinzipien in Anwendungen und Routinen des Arbeitsalltags und des Innovierens. Erfolgreiche Spielmechanismen, die in Form von Onlinespielen Millionen regelm\u00e4\u00dfig fesseln, werden bei Gamification in den Job \u00fcbertragen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Spielerische Wissens- und Erfahrungsvermittlung f\u00fcr Teams in einer Transformation<\/p>\n","protected":false},"featured_media":46280,"template":"","meta":{"_surecart_dashboard_logo_width":"180px","_surecart_dashboard_show_logo":true,"_surecart_dashboard_navigation_orders":true,"_surecart_dashboard_navigation_invoices":true,"_surecart_dashboard_navigation_subscriptions":true,"_surecart_dashboard_navigation_downloads":true,"_surecart_dashboard_navigation_billing":true,"_surecart_dashboard_navigation_account":true,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"working-guide":[],"transformation-blocks":[61,66],"innovation-stage":[54],"class_list":["post-41914","methode","type-methode","status-publish","has-post-thumbnail","hentry","transformation-blocks-growing","transformation-blocks-exploring","innovation-stage-wirksam-in-allen-innovationsphasen"],"_links":{"self":[{"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/methode\/41914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/methode"}],"about":[{"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/types\/methode"}],"version-history":[{"count":0,"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/methode\/41914\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/media\/46280"}],"wp:attachment":[{"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/media?parent=41914"}],"wp:term":[{"taxonomy":"working-guide","embeddable":true,"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/working-guide?post=41914"},{"taxonomy":"transformation-blocks","embeddable":true,"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/transformation-blocks?post=41914"},{"taxonomy":"innovation-stage","embeddable":true,"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/innovation-stage?post=41914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}