{"id":45944,"date":"2022-05-24T13:59:39","date_gmt":"2022-05-24T13:59:39","guid":{"rendered":"https:\/\/g9hq0oamq8.onrocket.site\/?post_type=methode&#038;p=45944"},"modified":"2024-07-08T04:52:13","modified_gmt":"2024-07-08T04:52:13","slug":"sorgen-auf-den-tisch-wicked-questions","status":"publish","type":"methode","link":"https:\/\/www.innovation.wiki\/de\/method\/sorgen-auf-den-tisch-wicked-questions\/","title":{"rendered":"Sorgen auf den Tisch\/Wicked Questions"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201eSorgen auf dem Tisch\u201c ist ein gefl\u00fcgeltes Wort aus dem Doppelkopf: In dem Kartenspiel gibt es besondere Bl\u00e4tter mit hohen Punktwerten, die den Mitspielern zugespielt werden m\u00fcssen, damit man sie gemeinsam f\u00fcr die Wertung ber\u00fccksichtigen kann. L\u00e4uft eine Partie mal nicht gut, oder hat man ein schlechtes Blatt auf der Hand, sollte man nach der Faustregel \u201eSorgen auf den Tisch\u201c m\u00f6glichst bald die wichtigen Karten in den Umlauf bringen \u2013 damit die Mitspieler eine Chance bekommen, sie als Trumpf\u00a0f\u00fcr das Team mitzunehmen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch in Transformations-Projekten gibt es oft Themen, die zu Beginn vertrackt erscheinen. Man wei\u00df nicht richtig, wie man sie angehen und unterbringen soll; manchmal finden die Mitwirkenden auch nicht den richtigen Weg, sie in Worte zu fassen. \u201eH\u00e4ttest du das doch mal fr\u00fcher signalisiert\u201c \u2013 diesen Vorwurf m\u00f6chte mantunlichst vermeiden. Auch f\u00fcr eine wertsch\u00e4tzende Team-Kultur ist es wichtig, von Beginn an die Bedenken aus dem Team ernst zu nehmen und bestenfalls als kreativen Aufh\u00e4nger zu nutzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hier kommen die \u201eWicked Questions\u201c in Spiel: Mit der Methode aus den Liberating Structures lassen sich paradox erscheinende Konstellationen erkennen, thematisieren und L\u00f6sungsans\u00e4tze daf\u00fcr ermitteln. So bekommt man den Dreh, um solche Themen auf den Tisch zu bringen. Anf\u00e4ngliche Sorgen m\u00fcssen das Projekt-Team nicht unausgesprochen belasten, sondern k\u00f6nnen zum Ausgangspunkt von Kreativit\u00e4t werden. Insbesondere in Change-Prozessen lassen sich aus widerspr\u00fcchlich wirkenden Einfl\u00fcssen so Kr\u00e4fte entfalten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sorgen und Problemstellungen wahrnehmen und paradoxe Fragestellungen als kreativen Ausgangspunkt nutzen.<\/p>\n","protected":false},"featured_media":45945,"template":"","meta":{"_surecart_dashboard_logo_width":"180px","_surecart_dashboard_show_logo":true,"_surecart_dashboard_navigation_orders":true,"_surecart_dashboard_navigation_invoices":true,"_surecart_dashboard_navigation_subscriptions":true,"_surecart_dashboard_navigation_downloads":true,"_surecart_dashboard_navigation_billing":true,"_surecart_dashboard_navigation_account":true,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"working-guide":[],"transformation-blocks":[57,64,59,58,61,60,62,65,66,63],"innovation-stage":[],"class_list":["post-45944","methode","type-methode","status-publish","has-post-thumbnail","hentry","transformation-blocks-leading","transformation-blocks-scaling","transformation-blocks-organizing","transformation-blocks-connecting","transformation-blocks-growing","transformation-blocks-talking","transformation-blocks-scanning","transformation-blocks-exploiting","transformation-blocks-exploring","transformation-blocks-earning"],"_links":{"self":[{"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/methode\/45944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/methode"}],"about":[{"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/types\/methode"}],"version-history":[{"count":0,"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/methode\/45944\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/media\/45945"}],"wp:attachment":[{"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/media?parent=45944"}],"wp:term":[{"taxonomy":"working-guide","embeddable":true,"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/working-guide?post=45944"},{"taxonomy":"transformation-blocks","embeddable":true,"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/transformation-blocks?post=45944"},{"taxonomy":"innovation-stage","embeddable":true,"href":"https:\/\/www.innovation.wiki\/de\/wp-json\/wp\/v2\/innovation-stage?post=45944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}